{"id":146,"count":3,"description":"","link":"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/","name":"technology","slug":"technology-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>technology Archives - VRtuale<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"technology Archives - VRtuale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/\" \/>\n<meta property=\"og:site_name\" content=\"VRtuale\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vrtuale.com\/wp-content\/uploads\/2024\/04\/Coderblock_only-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/\",\"url\":\"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/\",\"name\":\"technology Archives - VRtuale\",\"isPartOf\":{\"@id\":\"https:\/\/www.vrtuale.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vrtuale.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"technology\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vrtuale.com\/en\/#website\",\"url\":\"https:\/\/www.vrtuale.com\/en\/\",\"name\":\"vrtuale.com\",\"description\":\"VR &amp; XR Experiences for business\",\"publisher\":{\"@id\":\"https:\/\/www.vrtuale.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vrtuale.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vrtuale.com\/en\/#organization\",\"name\":\"Coderblock\",\"url\":\"https:\/\/www.vrtuale.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.vrtuale.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vrtuale.com\/wp-content\/uploads\/2024\/04\/cropped-Coderblock_only-logo.png\",\"contentUrl\":\"https:\/\/www.vrtuale.com\/wp-content\/uploads\/2024\/04\/cropped-Coderblock_only-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Coderblock\"},\"image\":{\"@id\":\"https:\/\/www.vrtuale.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vrtuale\",\"https:\/\/www.instagram.com\/vrtuale_\/\",\"https:\/\/linkedin.com\/company\/vrtuale\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"technology Archives - VRtuale","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"technology Archives - VRtuale","og_url":"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/","og_site_name":"VRtuale","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vrtuale.com\/wp-content\/uploads\/2024\/04\/Coderblock_only-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/","url":"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/","name":"technology Archives - VRtuale","isPartOf":{"@id":"https:\/\/www.vrtuale.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vrtuale.com\/en\/tag\/technology-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vrtuale.com\/en\/"},{"@type":"ListItem","position":2,"name":"technology"}]},{"@type":"WebSite","@id":"https:\/\/www.vrtuale.com\/en\/#website","url":"https:\/\/www.vrtuale.com\/en\/","name":"vrtuale.com","description":"VR &amp; XR Experiences for business","publisher":{"@id":"https:\/\/www.vrtuale.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vrtuale.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.vrtuale.com\/en\/#organization","name":"Coderblock","url":"https:\/\/www.vrtuale.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vrtuale.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.vrtuale.com\/wp-content\/uploads\/2024\/04\/cropped-Coderblock_only-logo.png","contentUrl":"https:\/\/www.vrtuale.com\/wp-content\/uploads\/2024\/04\/cropped-Coderblock_only-logo.png","width":512,"height":512,"caption":"Coderblock"},"image":{"@id":"https:\/\/www.vrtuale.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vrtuale","https:\/\/www.instagram.com\/vrtuale_\/","https:\/\/linkedin.com\/company\/vrtuale"]}]}},"_links":{"self":[{"href":"https:\/\/www.vrtuale.com\/en\/wp-json\/wp\/v2\/tags\/146"}],"collection":[{"href":"https:\/\/www.vrtuale.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.vrtuale.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.vrtuale.com\/en\/wp-json\/wp\/v2\/posts?tags=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}